{"id":12009,"date":"2019-03-08T11:17:38","date_gmt":"2019-03-08T10:17:38","guid":{"rendered":"http:\/\/megatrend.edu.rs\/student\/?p=12009"},"modified":"2019-03-08T11:17:50","modified_gmt":"2019-03-08T10:17:50","slug":"rezultati-ispita-finansijski-menadzment","status":"publish","type":"post","link":"https:\/\/megatrend.edu.rs\/student\/rezultati-ispita-finansijski-menadzment\/","title":{"rendered":"Rezultati ispita &#8211; finansijski menad\u017ement"},"content":{"rendered":"<p><a href=\"http:\/\/megatrend.edu.rs\/student\/wp-content\/uploads\/2019\/03\/finansijski-menadzment.pdf\">Rezultati<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rezultati<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"link","meta":[],"categories":[189],"tags":[],"_links":{"self":[{"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/posts\/12009"}],"collection":[{"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/comments?post=12009"}],"version-history":[{"count":2,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/posts\/12009\/revisions"}],"predecessor-version":[{"id":12011,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/posts\/12009\/revisions\/12011"}],"wp:attachment":[{"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/media?parent=12009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/categories?post=12009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/megatrend.edu.rs\/student\/wp-json\/wp\/v2\/tags?post=12009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}